{"id":2246,"date":"2018-11-10T11:22:48","date_gmt":"2018-11-10T11:22:48","guid":{"rendered":"https:\/\/www.wintechitalia.it\/new\/biot-2018\/"},"modified":"2018-11-10T11:22:48","modified_gmt":"2018-11-10T11:22:48","slug":"biot-2018","status":"publish","type":"post","link":"https:\/\/www.wintechitalia.it\/en\/biot-2018\/","title":{"rendered":"BIOT 2018"},"content":{"rendered":"<p><span title=\"\">Dall&#8217;<strong>11 al 14 dicembre 2018<\/strong>, Mosca diventa il luogo per la tradizionale <strong>Fiera internazionale della sicurezza e della protezione del lavoro (BIOT)<\/strong> giunta alla XXII edizione.<\/span> <span title=\"\">Le principali aziende russe e straniere, che operano nel settore della protezione del lavoro e della sicurezza industriale, si riuniranno sotto il tetto del padiglione 75 del centro espositivo VDNH.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-2237\" src=\"https:\/\/www.wintechitalia.it\/wp-content\/uploads\/2018\/12\/BIOT_1-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.wintechitalia.it\/wp-content\/uploads\/2018\/12\/BIOT_1-225x300.jpg 225w, https:\/\/www.wintechitalia.it\/wp-content\/uploads\/2018\/12\/BIOT_1-768x1024.jpg 768w, https:\/\/www.wintechitalia.it\/wp-content\/uploads\/2018\/12\/BIOT_1-600x800.jpg 600w, https:\/\/www.wintechitalia.it\/wp-content\/uploads\/2018\/12\/BIOT_1.jpg 792w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/> \u00a0 \u00a0 \u00a0 <img loading=\"lazy\" class=\"alignnone size-medium wp-image-2233\" src=\"https:\/\/www.wintechitalia.it\/wp-content\/uploads\/2018\/12\/BIOT_2-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.wintechitalia.it\/wp-content\/uploads\/2018\/12\/BIOT_2-225x300.jpg 225w, https:\/\/www.wintechitalia.it\/wp-content\/uploads\/2018\/12\/BIOT_2-768x1024.jpg 768w, https:\/\/www.wintechitalia.it\/wp-content\/uploads\/2018\/12\/BIOT_2-600x800.jpg 600w, https:\/\/www.wintechitalia.it\/wp-content\/uploads\/2018\/12\/BIOT_2.jpg 792w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dall&#8217;11 al 14 dicembre 2018, Mosca diventa il luogo per la tradizionale Fiera internazionale della sicurezza e della protezione del lavoro (BIOT) giunta alla XXII edizione. Le principali aziende russe e straniere, che operano nel settore della protezione del lavoro e della sicurezza industriale, si riuniranno sotto il tetto del padiglione 75 del centro espositivo [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/www.wintechitalia.it\/en\/biot-2018\/\">Read More&#8230;<span class=\"screen-reader-text\"> from BIOT 2018<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":2243,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.wintechitalia.it\/en\/wp-json\/wp\/v2\/posts\/2246"}],"collection":[{"href":"https:\/\/www.wintechitalia.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wintechitalia.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wintechitalia.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wintechitalia.it\/en\/wp-json\/wp\/v2\/comments?post=2246"}],"version-history":[{"count":0,"href":"https:\/\/www.wintechitalia.it\/en\/wp-json\/wp\/v2\/posts\/2246\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wintechitalia.it\/en\/wp-json\/wp\/v2\/media\/2243"}],"wp:attachment":[{"href":"https:\/\/www.wintechitalia.it\/en\/wp-json\/wp\/v2\/media?parent=2246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wintechitalia.it\/en\/wp-json\/wp\/v2\/categories?post=2246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wintechitalia.it\/en\/wp-json\/wp\/v2\/tags?post=2246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}